{"id":53288,"date":"2016-11-30T11:40:00","date_gmt":"2016-11-30T16:40:00","guid":{"rendered":"http:\/\/hardrockhaven.net\/online\/?p=53288"},"modified":"2016-11-30T14:48:44","modified_gmt":"2016-11-30T19:48:44","slug":"live-foreigner-concert-review-photo-gallery","status":"publish","type":"post","link":"http:\/\/hardrockhaven.net\/online\/2016\/live-foreigner-concert-review-photo-gallery\/","title":{"rendered":"LIVE! | Foreigner"},"content":{"rendered":"<blockquote><p><span style=\"text-decoration: underline;\">by Michael Allen<\/span><br \/>\n&#8211; Guest Columnist &#8212;<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53305\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2016\/11\/Foreigner-2016-GDA-52.jpg\" alt=\"foreigner-2016-gda-52\" width=\"800\" height=\"600\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2016\/11\/Foreigner-2016-GDA-52.jpg 800w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2016\/11\/Foreigner-2016-GDA-52-350x263.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2016\/11\/Foreigner-2016-GDA-52-768x576.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2016\/11\/Foreigner-2016-GDA-52-500x375.jpg 500w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2016\/11\/Foreigner-2016-GDA-52-174x131.jpg 174w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2016\/11\/Foreigner-2016-GDA-52-300x225.jpg 300w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2016\/11\/Foreigner-2016-GDA-52-70x53.jpg 70w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>November 18, 2016 at The Carlsen Center in Overland Park Kan. &#8212;<\/h3>\n<p>Say what you will about Foreigner, but, at this point, a lot of people consider it a cover band. Jeff Pilson and Kelly Hansen have been in the band for nearly 13 years. As for Mick Jones, well, it&#8217;s his band. The sax player\/guitarist Thom Gimbel has been with the group for 23 years. Pilson, Hansen, Gimbel and Jones have been in Foreigner longer than the &#8220;original&#8221; lineup. Additionally, guitarist Bruce Watson has been with Foreigner for nine years.<\/p>\n<p>Although the argument can be made that there&#8217;s not much original music from this new incarnation, that&#8217;s not really the band&#8217;s fault. It&#8217;s timing. Sadly, there&#8217;s no real market for new music from Classic Rock bands on today&#8217;s Rock radio. In 2009, Foreigner produced the album <em>Can&#8217;t Slow Down<\/em> with two hit singles, &#8220;In Pieces&#8221; and &#8220;Too Late.\u201d But Foreigner tours pretty much year round. At 70, Jones still kicks ass with the attitude of a budding musician, still trying to prove a point.<\/p>\n<p>At the Johnson County Community College in Overland Park Kan., Foreigner put on a really nice, intimate stripped-down acoustic performance that showcased all its hits and a couple of newer songs.<\/p>\n<p>The show started off with \u201cDouble Vision,\u201d and from the beginning of the show, Hansen established himself as a very powerful front man with vocals that, at times, resembled a tenor sax. Although it&#8217;s easy to get lost in the &#8220;Lou Gramm needs to be here&#8221; feeling, a few bars in, you realize that Hansen is more than apt and able to paint a picture every bit as bright as Lou Gramm. Songs like &#8220;Long Long Way From Home&#8221; and &#8220;Waiting For A Girl Like You&#8221; were performed perfectly.<\/p>\n<p>Foreigner performed a couple newer songs; one from <em>Can&#8217;t Slow Down<\/em> called &#8220;When It Comes To Love,&#8221; which features smoothly blended lead and harmony vocals and a nice sax solo from Gimbel. Another newer song &#8220;Flame Still Burns,&#8221; which Jones claims was written for a movie soundtrack, was reminiscent of vintage Foreigner.<\/p>\n<p>All in all, the energy of Foreigner&#8217;s show was incredible. The musicianship was stellar, and the overall vibe of the show was, as always, very exciting. One can only hope that they&#8217;ve only begun to hit their stride in this version of the band. The show ended with &#8220;Juke Box Hero,&#8221; &#8220;Hot Blooded&#8221; and &#8220;I Want To Know What Love Is,&#8221; and were performed perfectly.<\/p>\n<p>This was a must-see concert for any new or longtime Foreigner fan. The band put on a very impressive and memorable show.<\/p>\n<h3>LIVE! | Foreigner Photo Gallery<\/h3>\n    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"1\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/online\/wp-json\/wp\/v2\/posts\/53288\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=131&#038;tag=0&#038;theme_id=1&#038;shortcode_id=134&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F53288\"         data-gallery-id=\"131\"         data-popup-width=\"640\"         data-popup-height=\"480\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"134\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"131\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"3\"         data-thumbnail-width=\"180\"         data-bwg=\"0\"         data-gallery-id=\"131\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=131&amp;tag=0&amp;theme_id=1&amp;shortcode_id=134&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F53288\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6283\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_02.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6283\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_02.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_02.JPG\"                   alt=\"Foreigner 2016 GDA 02\"                   title=\"Foreigner 2016 GDA 02\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6282\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_01.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6282\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_01.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_01.JPG\"                   alt=\"Foreigner 2016 GDA 01\"                   title=\"Foreigner 2016 GDA 01\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6281\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_08.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6281\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_08.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_08.JPG\"                   alt=\"Foreigner 2016 GDA 08\"                   title=\"Foreigner 2016 GDA 08\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6280\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_06.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6280\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_06.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_06.JPG\"                   alt=\"Foreigner 2016 GDA 06\"                   title=\"Foreigner 2016 GDA 06\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6279\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_05.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6279\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_05.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_05.JPG\"                   alt=\"Foreigner 2016 GDA 05\"                   title=\"Foreigner 2016 GDA 05\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6278\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_03.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6278\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_03.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_03.JPG\"                   alt=\"Foreigner 2016 GDA 03\"                   title=\"Foreigner 2016 GDA 03\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6277\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_07.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6277\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_07.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_07.JPG\"                   alt=\"Foreigner 2016 GDA 07\"                   title=\"Foreigner 2016 GDA 07\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6276\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_11.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6276\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_11.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_11.JPG\"                   alt=\"Foreigner 2016 GDA 11\"                   title=\"Foreigner 2016 GDA 11\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6275\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_12.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6275\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_12.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_12.JPG\"                   alt=\"Foreigner 2016 GDA 12\"                   title=\"Foreigner 2016 GDA 12\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6274\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_09.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6274\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_09.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_09.JPG\"                   alt=\"Foreigner 2016 GDA 09\"                   title=\"Foreigner 2016 GDA 09\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6273\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_13.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6273\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_13.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_13.JPG\"                   alt=\"Foreigner 2016 GDA 13\"                   title=\"Foreigner 2016 GDA 13\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6272\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_14.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6272\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_14.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_14.JPG\"                   alt=\"Foreigner 2016 GDA 14\"                   title=\"Foreigner 2016 GDA 14\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6271\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_19.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6271\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_19.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_19.JPG\"                   alt=\"Foreigner 2016 GDA 19\"                   title=\"Foreigner 2016 GDA 19\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6270\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_10.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6270\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_10.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_10.JPG\"                   alt=\"Foreigner 2016 GDA 10\"                   title=\"Foreigner 2016 GDA 10\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"6269\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/Foreigner_2016_GDA_22.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"6269\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_22.JPG\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2016\/2016%20Foreigner%20GDA\/thumb\/Foreigner_2016_GDA_22.JPG\"                   alt=\"Foreigner 2016 GDA 22\"                   title=\"Foreigner 2016 GDA 22\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>          <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                      <span class=\"pagination-links_0 pagination-links\" data-pages-count=\"3\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Go to the first page\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Go to the previous page\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_0\" onkeypress=\"return bwg_change_page_0(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tof\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_0\">\t\t\t\t\t\t\t\t\t\t\t3\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-0\" title=\"Go to the next page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/53288?page_number_0=2\">\u203a<\/a>                <a class=\"bwg-a last-page-0\" title=\"Go to the last page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/53288?page_number_0=3\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 3;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>                <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1891071009\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n<p>Visit Foreigner online: <a href=\"http:\/\/www.foreigneronline.com\/\" target=\"_blank\">http:\/\/www.foreigneronline.com\/<\/a><\/p>\n<p><em>Photos appear courtesy of Gary Dean Ash.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">by Michael Allen &#8211; Guest Columnist &#8212; November 18, 2016 at The Carlsen Center in Overland Park Kan. &#8212; Say what you will about Foreigner, but, at this point, a lot of people consider it <a class=\"mh-excerpt-more\" href=\"http:\/\/hardrockhaven.net\/online\/2016\/live-foreigner-concert-review-photo-gallery\/\" title=\"LIVE! | Foreigner\">[&#8230;]<\/a><\/div>\n","protected":false},"author":10,"featured_media":53306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13654],"tags":[674,163,4782,9162,164,9161,4221,334],"class_list":{"0":"post-53288","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arcconrvw2016","8":"tag-concert","9":"tag-foreigner","10":"tag-jeff-pilson","11":"tag-kelly-hansen","12":"tag-live","13":"tag-mick-jones","14":"tag-photo-gallery","15":"tag-review"},"_links":{"self":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts\/53288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/comments?post=53288"}],"version-history":[{"count":0,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts\/53288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/media\/53306"}],"wp:attachment":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/media?parent=53288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/categories?post=53288"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/tags?post=53288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}