{"id":54843,"date":"2017-06-15T19:32:35","date_gmt":"2017-06-16T00:32:35","guid":{"rendered":"http:\/\/hardrockhaven.net\/online\/?p=54843"},"modified":"2017-06-15T19:59:41","modified_gmt":"2017-06-16T00:59:41","slug":"the-birthday-massacre-army-of-the-universe-with-sumo-cyco-concert-review-photo-gallery","status":"publish","type":"post","link":"http:\/\/hardrockhaven.net\/online\/2017\/the-birthday-massacre-army-of-the-universe-with-sumo-cyco-concert-review-photo-gallery\/","title":{"rendered":"The Birthday Massacre, Army of the Universe with Sumo Cyco"},"content":{"rendered":"<blockquote><p><span style=\"text-decoration: underline;\">by Tamara Igleheart<\/span><br \/>\n&#8212; Photojournalist &#8212;<\/p><\/blockquote>\n<h3>June 3, 2017 at the Roxy Theater in Los Angeles, CA. &#8212;<\/h3>\n<p>The Sunset Strip was shaken to the core as the Under Your Spell tour rolled through town on June 3. Three phenomenal bands threw down on the stage of the Roxy Theater in the heart of Hollywood, Calif., headlined by the rock\/synthpop band, The Birthday Massacre. The band is currently touring in support of their newest release, Under Your Spell, which dropped on June 9. Sharing the stage with them were the Canadian four-piece, Sumo Cyco, and Italy\u2019s own Army of the Universe. This perfect musical storm proved to provide a night filled with great music and high energy.<\/p>\n<figure id=\"attachment_54884\" aria-describedby=\"caption-attachment-54884\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/SC15v2.jpg\" alt=\"\" width=\"800\" height=\"532\" class=\"size-full wp-image-54884\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/SC15v2.jpg 800w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/SC15v2-350x233.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/SC15v2-768x511.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/SC15v2-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-54884\" class=\"wp-caption-text\">Sumo Cyco: Skye Sweetnam<\/figcaption><\/figure>\n<p>Sumo Cyco were the first to command the stage at the Roxy. The band combines elements of punk and metal, both of which shine through in their live performance. frontwoman Skye Sweetnam seemed to have endless energy as she bounded and danced across the stage. Her voice had a wonderful range and tone, and she was even able to get gritty and growl like the best of them. Guitarist Matt Drake and bassist Oscar Anesetti also helped to keep up liveliness with catchy guitar and bass licks. Drummer Matt Trozzi is a powerhouse behind the drums and fits in with the rest of his bandmates exceptionally well even though he is the newest member. There were a few separate occasions when Skye joined the crowd on the pit floor and even rode through it on Drake\u2019s shoulders. If one thing is for sure, it is that this band is entertaining to watch! The group exemplifies many different styles, and listeners across several different spectrums of music can find something to like about Sumo Cyco. Their newest record, Opus Mar, is available now.<\/p>\n<figure id=\"attachment_54886\" aria-describedby=\"caption-attachment-54886\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/AOU20.jpg\" alt=\"\" width=\"800\" height=\"532\" class=\"size-full wp-image-54886\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/AOU20.jpg 800w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/AOU20-350x233.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/AOU20-768x511.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/AOU20-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-54886\" class=\"wp-caption-text\">Army of the Universe: Lord K<\/figcaption><\/figure>\n<p>Next up was Army of the Universe. These Italian electronic rockers have been busy, having just concluded the European leg of the Industrial Pop Tour in support of Aesthetic Perfection when the current tour with The Birthday Massacre was set to begin. When they played to a crowded Roxy Theater, it was easy to see why they have been gaining more traction and attention recently. 1999 and the Aftershow, Army of the Universe\u2019s most recent album, exudes an upbeat mood, and lead singer Lord K brought it to life before the audience. He utilized eccentric hand movements and danced to the music, which lent an illustrative element to their set. Dave Tavecchia served hard rock guitar riffs, and Giuseppe Amato unleashed brute force on his drum kit, which kept the patrons enthralled. Albert Vorne divided his time between delivering the keys from behind his setup and donning a key-tar so that he could captivate the crowd unhindered. From start to finish, there was never a boring moment during Army of the Universe\u2019s set. It was impossible for even the most stubborn of wallflowers to refrain from moving to the beat!<\/p>\n<figure id=\"attachment_54888\" aria-describedby=\"caption-attachment-54888\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/TBM18.jpg\" alt=\"\" width=\"800\" height=\"532\" class=\"size-full wp-image-54888\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/TBM18.jpg 800w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/TBM18-350x233.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/TBM18-768x511.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/06\/TBM18-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-54888\" class=\"wp-caption-text\">The Birthday Massacre:  Chibi<\/figcaption><\/figure>\n<p>It was then time for the main event. If it were possible, it appeared that more people had filed into the already packed room, pressing toward the stage, eagerly awaiting the arrival of The Birthday Massacre upon it. While the anticipation continued to build, shouts of the band\u2019s name rang out loud and proud. This was clearly a group of people loved by many. The curtain went up, and out from the fog came The Birthday Massacre. From the very beginning, they displayed high energy, and it was obvious that they truly enjoy playing music for their fans. Chibi is an incredibly talented vocalist and frontwoman. She made everyone in the crowd feel welcome and waved to as many fans as she could, knowing that it meant the world to them. On guitar and backup vocals, Rainbow bleeds charisma, and his genuine smiles are contagious. Manning the other guitar, M. Falcore has a more relaxed stage presence; however, it does not diminish the fact that he is still euphoric while on stage with his friends. Owen could barely be contained behind the keyboard; he had so much vigor, in fact, that he switched to a key-tar so he could move around the stage. It is obvious that Nate Manor feels at home on the bass performing with the band, as he held the rhythm together. Nik Pesut stepped in to play drums for the North American tour when drummer Rhim could not go on the road with the band. Although Rhim was missed, Pesut never missed a beat! Despite the setback of having to find a drummer last minute to fill in for their tour, The Birthday Massacre gave a spectacular performance. The camaraderie that the band members show one another is truly incomparable and the love flowed out into the audience, which sang the lyrics back to Chibi with every song. The fans experienced an unforgettable night at the Los Angeles stop of the Under Your Spell tour!<\/p>\n<h3>The Birthday Massacre, Army of the Universe with Sumo Cyco Concert Photo Gallery<\/h3>\n    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"1\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/online\/wp-json\/wp\/v2\/posts\/54843\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=168&#038;tag=0&#038;theme_id=1&#038;shortcode_id=171&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F54843\"         data-gallery-id=\"168\"         data-popup-width=\"640\"         data-popup-height=\"480\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"171\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"168\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"5\"         data-thumbnail-width=\"180\"         data-bwg=\"0\"         data-gallery-id=\"168\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=168&amp;tag=0&amp;theme_id=1&amp;shortcode_id=171&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F54843\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7540\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM13.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7540\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM13.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM13.jpg\"                   alt=\"TBM13\"                   title=\"TBM13\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7539\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM17.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7539\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM17.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM17.jpg\"                   alt=\"TBM17\"                   title=\"TBM17\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7538\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM14.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7538\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM14.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM14.jpg\"                   alt=\"TBM14\"                   title=\"TBM14\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7537\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM15.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7537\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM15.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM15.jpg\"                   alt=\"TBM15\"                   title=\"TBM15\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7536\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM19.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7536\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM19.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM19.jpg\"                   alt=\"TBM19\"                   title=\"TBM19\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7535\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM20.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7535\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM20.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM20.jpg\"                   alt=\"TBM20\"                   title=\"TBM20\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7534\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM23.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7534\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM23.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM23.jpg\"                   alt=\"TBM23\"                   title=\"TBM23\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7533\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM22.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7533\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM22.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM22.jpg\"                   alt=\"TBM22\"                   title=\"TBM22\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7532\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM25.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7532\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM25.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM25.jpg\"                   alt=\"TBM25\"                   title=\"TBM25\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7531\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM24.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7531\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM24.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM24.jpg\"                   alt=\"TBM24\"                   title=\"TBM24\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7530\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM18.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7530\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM18.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM18.jpg\"                   alt=\"TBM18\"                   title=\"TBM18\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7529\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM1.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7529\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM1.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM1.jpg\"                   alt=\"TBM1\"                   title=\"TBM1\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7528\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM2.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7528\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM2.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM2.jpg\"                   alt=\"TBM2\"                   title=\"TBM2\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7527\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM16.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7527\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM16.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM16.jpg\"                   alt=\"TBM16\"                   title=\"TBM16\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7526\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM5.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7526\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM5.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM5.jpg\"                   alt=\"TBM5\"                   title=\"TBM5\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7525\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM3.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7525\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM3.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM3.jpg\"                   alt=\"TBM3\"                   title=\"TBM3\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7524\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM21.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7524\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM21.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM21.jpg\"                   alt=\"TBM21\"                   title=\"TBM21\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7523\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM6.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7523\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM6.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM6.jpg\"                   alt=\"TBM6\"                   title=\"TBM6\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7522\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM7.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7522\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM7.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM7.jpg\"                   alt=\"TBM7\"                   title=\"TBM7\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7521\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM8.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7521\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM8.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM8.jpg\"                   alt=\"TBM8\"                   title=\"TBM8\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7520\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM11.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7520\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM11.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM11.jpg\"                   alt=\"TBM11\"                   title=\"TBM11\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7519\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM4.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7519\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM4.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM4.jpg\"                   alt=\"TBM4\"                   title=\"TBM4\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7518\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU12.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7518\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU12.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU12.jpg\"                   alt=\"AOU12\"                   title=\"AOU12\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7517\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM9.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7517\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM9.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM9.jpg\"                   alt=\"TBM9\"                   title=\"TBM9\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7516\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU13.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7516\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU13.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU13.jpg\"                   alt=\"AOU13\"                   title=\"AOU13\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7515\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM10.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7515\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM10.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM10.jpg\"                   alt=\"TBM10\"                   title=\"TBM10\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7514\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/TBM12.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7514\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM12.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/TBM12.jpg\"                   alt=\"TBM12\"                   title=\"TBM12\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7513\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU14.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7513\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU14.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU14.jpg\"                   alt=\"AOU14\"                   title=\"AOU14\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7512\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU17.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7512\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU17.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU17.jpg\"                   alt=\"AOU17\"                   title=\"AOU17\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7511\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU16.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7511\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU16.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU16.jpg\"                   alt=\"AOU16\"                   title=\"AOU16\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7510\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU18.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7510\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU18.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU18.jpg\"                   alt=\"AOU18\"                   title=\"AOU18\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7509\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU19.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7509\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU19.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU19.jpg\"                   alt=\"AOU19\"                   title=\"AOU19\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7508\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU20.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7508\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU20.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU20.jpg\"                   alt=\"AOU20\"                   title=\"AOU20\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7507\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU1.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7507\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU1.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU1.jpg\"                   alt=\"AOU1\"                   title=\"AOU1\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7506\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU11.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7506\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU11.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU11.jpg\"                   alt=\"AOU11\"                   title=\"AOU11\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7505\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU15.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7505\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU15.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU15.jpg\"                   alt=\"AOU15\"                   title=\"AOU15\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7504\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU2.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7504\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU2.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU2.jpg\"                   alt=\"AOU2\"                   title=\"AOU2\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7503\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU5.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7503\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU5.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU5.jpg\"                   alt=\"AOU5\"                   title=\"AOU5\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7502\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU4.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7502\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU4.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU4.jpg\"                   alt=\"AOU4\"                   title=\"AOU4\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7501\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/AOU9.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7501\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU9.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Birthday_Massacre_TI\/thumb\/AOU9.jpg\"                   alt=\"AOU9\"                   title=\"AOU9\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>          <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                      <span class=\"pagination-links_0 pagination-links\" data-pages-count=\"2\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Go to the first page\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Go to the previous page\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_0\" onkeypress=\"return bwg_change_page_0(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tof\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_0\">\t\t\t\t\t\t\t\t\t\t\t2\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-0\" title=\"Go to the next page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/54843?page_number_0=2\">\u203a<\/a>                <a class=\"bwg-a last-page-0\" title=\"Go to the last page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/54843?page_number_0=2\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 2;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>                <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"695985448\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n<p>Connect with:<br \/>\nSumo Cyco here: <a href=\"http:\/\/sumocyco.com\/cycocity\/\" target=\"_blank\">http:\/\/sumocyco.com\/cycocity\/<\/a><br \/>\nArmy of the Universe here: <a href=\"http:\/\/www.armyoftheuniverse.com\/\" target=\"_blank\">http:\/\/www.armyoftheuniverse.com\/<\/a><br \/>\nThe Birthday Massacre here: <a href=\"http:\/\/thebirthdaymassacre.com\/\" target=\"_blank\">http:\/\/thebirthdaymassacre.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">by Tamara Igleheart &#8212; Photojournalist &#8212; June 3, 2017 at the Roxy Theater in Los Angeles, CA. &#8212; The Sunset Strip was shaken to the core as the Under Your Spell tour rolled through town <a class=\"mh-excerpt-more\" href=\"http:\/\/hardrockhaven.net\/online\/2017\/the-birthday-massacre-army-of-the-universe-with-sumo-cyco-concert-review-photo-gallery\/\" title=\"The Birthday Massacre, Army of the Universe with Sumo Cyco\">[&#8230;]<\/a><\/div>\n","protected":false},"author":10,"featured_media":54884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15122],"tags":[13379,674,16,3849,334,13380,11854],"class_list":{"0":"post-54843","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arcconrvw2017","8":"tag-army-of-the-universe","9":"tag-concert","10":"tag-image-gallery","11":"tag-photo","12":"tag-review","13":"tag-sumo-cyco","14":"tag-the-birthday-massacre"},"_links":{"self":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts\/54843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/comments?post=54843"}],"version-history":[{"count":0,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts\/54843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/media\/54884"}],"wp:attachment":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/media?parent=54843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/categories?post=54843"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/tags?post=54843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}