{"id":55719,"date":"2017-10-24T12:34:42","date_gmt":"2017-10-24T17:34:42","guid":{"rendered":"http:\/\/hardrockhaven.net\/online\/?p=55719"},"modified":"2018-03-25T18:13:06","modified_gmt":"2018-03-25T23:13:06","slug":"mammothfest-2017-concert-review-photo-gallery","status":"publish","type":"post","link":"http:\/\/hardrockhaven.net\/online\/2017\/mammothfest-2017-concert-review-photo-gallery\/","title":{"rendered":"Mammothfest 2017"},"content":{"rendered":"<blockquote><p><span style=\"text-decoration: underline;\">by Arta Gailuma<\/span><br \/>\n&#8211; Photojournalist &#8212;<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-55726\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Mammothfest-2017.jpg\" alt=\"\" width=\"960\" height=\"318\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Mammothfest-2017.jpg 960w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Mammothfest-2017-350x116.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Mammothfest-2017-768x254.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Mammothfest-2017-500x166.jpg 500w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<h3>October 6 &#8211; 8, 2017 at The Arch in Brighton, England, UK &#8212;<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/The-Infernal-Sea-d1.jpg\" alt=\"\" width=\"959\" height=\"400\" class=\"aligncenter size-full wp-image-55733\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/The-Infernal-Sea-d1.jpg 959w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/The-Infernal-Sea-d1-350x146.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/The-Infernal-Sea-d1-768x320.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/The-Infernal-Sea-d1-500x209.jpg 500w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><\/p>\n<p>Friday was the shortest day but featured the biggest crowds to witness the Metal assault of Norwegian Black Metallers Tsjuder and an exclusive UK appearance from the mighty Greek Black Metal titans Rotting Christ.<\/p>\n<h3>Mammothfest 2017 Day 1 Photo Gallery<\/h3>\n    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"1\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/online\/wp-json\/wp\/v2\/posts\/55719\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=190&#038;tag=0&#038;theme_id=1&#038;shortcode_id=197&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F55719\"         data-gallery-id=\"190\"         data-popup-width=\"800\"         data-popup-height=\"600\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"197\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"190\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"6\"         data-thumbnail-width=\"180\"         data-bwg=\"0\"         data-gallery-id=\"190\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=190&amp;tag=0&amp;theme_id=1&amp;shortcode_id=197&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F55719\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8910\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Deitus.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8910\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Deitus.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Deitus.jpg\"                   alt=\"Deitus\"                   title=\"Deitus\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deitus<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8909\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Ethereal.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8909\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Ethereal.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Ethereal.jpg\"                   alt=\"Ethereal\"                   title=\"Ethereal\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ethereal<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8908\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Ethereal03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8908\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Ethereal03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Ethereal03.jpg\"                   alt=\"Ethereal\"                   title=\"Ethereal\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ethereal<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8907\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Ethereal02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8907\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Ethereal02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Ethereal02.jpg\"                   alt=\"Ethereal\"                   title=\"Ethereal\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ethereal<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8906\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Ethereal01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8906\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Ethereal01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Ethereal01.jpg\"                   alt=\"Ethereal\"                   title=\"Ethereal\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ethereal<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8905\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Deitus01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8905\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Deitus01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Deitus01.jpg\"                   alt=\"Deitus\"                   title=\"Deitus\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deitus<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8904\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Necronautical.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8904\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Necronautical.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Necronautical.jpg\"                   alt=\"Necronautical\"                   title=\"Necronautical\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Necronautical<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8903\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Heathen_Deity01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8903\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Heathen_Deity01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Heathen_Deity01.jpg\"                   alt=\"Heathen Deity\"                   title=\"Heathen Deity\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Heathen Deity<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8902\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Heathen_Deity.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8902\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Heathen_Deity.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Heathen_Deity.jpg\"                   alt=\"Heathen Deity\"                   title=\"Heathen Deity\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Heathen Deity<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8901\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Heathen_Deity02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8901\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Heathen_Deity02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Heathen_Deity02.jpg\"                   alt=\"Heathen Deity\"                   title=\"Heathen Deity\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Heathen Deity<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8900\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Necronautical03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8900\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Necronautical03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Necronautical03.jpg\"                   alt=\"Necronautical\"                   title=\"Necronautical\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Necronautical<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8899\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Necronautical01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8899\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Necronautical01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Necronautical01.jpg\"                   alt=\"Necronautical\"                   title=\"Necronautical\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Necronautical<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8898\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Rotting_Christ02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8898\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ02.jpg\"                   alt=\"Rotting Christ\"                   title=\"Rotting Christ\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Rotting Christ<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8897\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Rotting_Christ.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8897\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ.jpg\"                   alt=\"Rotting Christ\"                   title=\"Rotting Christ\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Rotting Christ<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8896\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Rotting_Christ01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8896\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ01.jpg\"                   alt=\"Rotting Christ\"                   title=\"Rotting Christ\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Rotting Christ<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8895\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Necronautical02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8895\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Necronautical02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Necronautical02.jpg\"                   alt=\"Necronautical\"                   title=\"Necronautical\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Necronautical<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8894\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Rotting_Christ06.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8894\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ06.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ06.jpg\"                   alt=\"Rotting Christ\"                   title=\"Rotting Christ\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Rotting Christ<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8893\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Rotting_Christ03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8893\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ03.jpg\"                   alt=\"Rotting Christ\"                   title=\"Rotting Christ\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Rotting Christ<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8892\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Rotting_Christ05.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8892\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ05.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ05.jpg\"                   alt=\"Rotting Christ\"                   title=\"Rotting Christ\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Rotting Christ<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8891\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/The_Infernal_Sea.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8891\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea.jpg\"                   alt=\"The Infernal Sea\"                   title=\"The Infernal Sea\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">The Infernal Sea<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8890\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/The_Infernal_Sea02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8890\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea02.jpg\"                   alt=\"The Infernal Sea\"                   title=\"The Infernal Sea\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">The Infernal Sea<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8889\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/The_Infernal_Sea01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8889\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea01.jpg\"                   alt=\"The Infernal Sea\"                   title=\"The Infernal Sea\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">The Infernal Sea<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8888\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/The_Infernal_Sea03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8888\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea03.jpg\"                   alt=\"The Infernal Sea\"                   title=\"The Infernal Sea\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">The Infernal Sea<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8887\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Rotting_Christ04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8887\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Rotting_Christ04.jpg\"                   alt=\"Rotting Christ\"                   title=\"Rotting Christ\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Rotting Christ<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8886\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Steve.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8886\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Steve.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Steve.jpg\"                   alt=\"Steve\"                   title=\"Steve\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Steve<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8885\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Tsjuder.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8885\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Tsjuder.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Tsjuder.jpg\"                   alt=\"Tsjuder\"                   title=\"Tsjuder\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Tsjuder<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8884\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Tsjuder02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8884\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Tsjuder02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Tsjuder02.jpg\"                   alt=\"Tsjuder\"                   title=\"Tsjuder\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Tsjuder<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8883\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Tsjuder01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8883\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Tsjuder01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Tsjuder01.jpg\"                   alt=\"Tsjuder\"                   title=\"Tsjuder\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Tsjuder<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8882\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/Tsjuder03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8882\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Tsjuder03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/Tsjuder03.jpg\"                   alt=\"Tsjuder\"                   title=\"Tsjuder\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Tsjuder<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8881\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/The_Infernal_Sea04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"8881\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D1_AG\/thumb\/The_Infernal_Sea04.jpg\"                   alt=\"The Infernal Sea\"                   title=\"The Infernal Sea\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">The Infernal Sea<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>          <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                      <span class=\"pagination-links_0 pagination-links\" data-pages-count=\"2\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Go to the first page\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Go to the previous page\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_0\" onkeypress=\"return bwg_change_page_0(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tof\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_0\">\t\t\t\t\t\t\t\t\t\t\t2\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-0\" title=\"Go to the next page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/55719?page_number_0=2\">\u203a<\/a>                <a class=\"bwg-a last-page-0\" title=\"Go to the last page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/55719?page_number_0=2\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 2;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>                <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"298101287\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n<p>Day 1 Line-up &#8212;<\/p>\n<p>The Arch Stage (Black Metal)<br \/>\n18:00 Vehement<br \/>\n18:45 The Infernal Sea<br \/>\n19:45 Tsjuder<br \/>\n20:50 Rotting Christ<\/p>\n<p>Rickstock Stage<br \/>\n18:30 Necronautical<br \/>\n19:15 Heathen Deity<br \/>\n20:30 Ethereal<br \/>\n22:15 Deitus (VIP)<br \/>\n23:30 Sorrow Plagues (VIP)<\/p>\n<p><!--nextpage--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Meta-stasis-d2.jpg\" alt=\"\" width=\"959\" height=\"400\" class=\"aligncenter size-full wp-image-55731\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Meta-stasis-d2.jpg 959w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Meta-stasis-d2-350x146.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Meta-stasis-d2-768x320.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Meta-stasis-d2-500x209.jpg 500w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><\/p>\n<p>Saturday was welcomed to the stage Meta-Statis, Abhorrent Decimation, Akercocke, Lawnmower Deth, whose drummer ended up being sick in the middle of their set, No Raza, a Death Metal band from Columbia, and Synaptik, British Heavy Metallers who are self-described as &#8212; <em>&#8220;Merging various metal genres including but not limited to Classic Rock, Classical, Prog, Tech, Thrash and Heavy Metal allows SYNAPTIK to explore unique avenues with toe-curling precision.&#8221; <\/em><\/p>\n<p>&#8220;Love or hate we are certain to stand out, our heavier than a black hole riffs with melodic clean vocals are something rarely heard, check out our music at <a href=\"http:\/\/www.synaptikmetal.com\" rel=\"noopener\" target=\"_blank\">www.synaptikmetal.com<\/a> or buy the album from HMV.&#8221;<\/p>\n<p>The night was headlined by none other than the epic Fleshgod Apocalypse.<\/p>\n<p>Another band that was worth checking out was Kill All The Gentlemen who have finished touring Eastern Europe and on its way to releasing new material, <em>&#8220;KATG are entering a new phase. With an upcoming album &#8216;The Loss and The Rapture&#8217; set for release later this year, the band is exploring darker subject matter than ever before. 8-tracks laced with vitriol and aggression, with new and exclusive artwork from renowned Peruvian artist, Jose Gabriel Alegr\u00eda Sabogal, this release will set the tone for U.K. Extreme Metal releases for 2018.&#8221;<\/em> &#8211; <a href=\"http:\/\/www.facebook.com\/killallthegentlemen\" rel=\"noopener\" target=\"_blank\">www.facebook.com\/killallthegentlemen<\/a>.<\/p>\n<p>By the end of the day the VIP&#8217;s were able to party with Australian pirates Lagerstein and the few with still some energy left go crazy with Seething Akira, who has been busy touring and recording: <em>&#8220;Off the back of our recent shows at Bloodstock and Victorious festival, we&#8217;re pleased to be putting the finishing touches to our debut album. The album has taken us some serious time, but we&#8217;re very excited to finally show everyone what we&#8217;ve been working on. With all this going on we&#8217;ll also be back in Belgium this December hitting 6Kfest in Liege. This along with Mammothfest in October is keeping us busy whilst we prep the album. We&#8217;ll also be releasing our second single off the album imminently, so keep your eyes peeled!&#8221;<\/em> &#8211; <a href=\"http:\/\/www.facebook.com\/killallthegentlemen\" rel=\"noopener\" target=\"_blank\">www.seethingakira.com<\/a>.<\/p>\n<h3>Mammothfest 2017 Day 2 Photo Gallery<\/h3>\n    <div id=\"bwg_container1_1\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"1\"         data-bwg=\"1\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/online\/wp-json\/wp\/v2\/posts\/55719\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=1&#038;gallery_id=191&#038;tag=0&#038;theme_id=1&#038;shortcode_id=198&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F55719\"         data-gallery-id=\"191\"         data-popup-width=\"800\"         data-popup-height=\"600\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_1\">             <div id=\"ajax_loading_1\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_1\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_1\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"1\"              data-shortcode-id=\"198\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"191\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_1\" class=\"bwg-background bwg-background-1\">                <div data-max-count=\"5\"         data-thumbnail-width=\"180\"         data-bwg=\"1\"         data-gallery-id=\"191\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=1&amp;gallery_id=191&amp;tag=0&amp;theme_id=1&amp;shortcode_id=198&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F55719\"         id=\"bwg_thumbnails_1\"         class=\"bwg-container-1 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8962\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Abhorrent_Decimation01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8962\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Abhorrent_Decimation01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Abhorrent_Decimation01.jpg\"                   alt=\"Abhorrent Decimation01\"                   title=\"Abhorrent Decimation01\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Abhorrent Decimation01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8961\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Akercocke01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8961\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Akercocke01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Akercocke01.jpg\"                   alt=\"Akercocke01\"                   title=\"Akercocke01\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Akercocke01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8960\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Abhorrent_Decimation.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8960\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Abhorrent_Decimation.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Abhorrent_Decimation.jpg\"                   alt=\"Abhorrent Decimation\"                   title=\"Abhorrent Decimation\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Abhorrent Decimation<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8959\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Akercocke.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8959\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Akercocke.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Akercocke.jpg\"                   alt=\"Akercocke\"                   title=\"Akercocke\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Akercocke<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8958\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Abhorrent_Decimation02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8958\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Abhorrent_Decimation02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Abhorrent_Decimation02.jpg\"                   alt=\"Abhorrent Decimation02\"                   title=\"Abhorrent Decimation02\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Abhorrent Decimation02<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8957\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Akercocke03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8957\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Akercocke03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Akercocke03.jpg\"                   alt=\"Akercocke03\"                   title=\"Akercocke03\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Akercocke03<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8956\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Abhorrent_Decimation03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8956\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Abhorrent_Decimation03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Abhorrent_Decimation03.jpg\"                   alt=\"Abhorrent Decimation03\"                   title=\"Abhorrent Decimation03\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Abhorrent Decimation03<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8955\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Akercocke02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8955\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Akercocke02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Akercocke02.jpg\"                   alt=\"Akercocke02\"                   title=\"Akercocke02\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Akercocke02<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8954\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Ascaris02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8954\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Ascaris02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Ascaris02.jpg\"                   alt=\"Ascaris02\"                   title=\"Ascaris02\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ascaris02<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8953\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Damaj.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8953\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Damaj.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Damaj.jpg\"                   alt=\"Damaj\"                   title=\"Damaj\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Damaj<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8952\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Ascaris.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8952\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Ascaris.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Ascaris.jpg\"                   alt=\"Ascaris\"                   title=\"Ascaris\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ascaris<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8951\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Bleed_Again.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8951\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Bleed_Again.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Bleed_Again.jpg\"                   alt=\"Bleed Again\"                   title=\"Bleed Again\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Bleed Again<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8950\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Ascaris01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8950\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Ascaris01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Ascaris01.jpg\"                   alt=\"Ascaris01\"                   title=\"Ascaris01\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ascaris01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8949\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Fleshgod_Apocalypse.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8949\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse.jpg\"                   alt=\"Fleshgod Apocalypse\"                   title=\"Fleshgod Apocalypse\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Fleshgod Apocalypse<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8948\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Dragged_Into_Sunlight01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8948\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Dragged_Into_Sunlight01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Dragged_Into_Sunlight01.jpg\"                   alt=\"Dragged Into Sunlight01\"                   title=\"Dragged Into Sunlight01\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Dragged Into Sunlight01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8947\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Fleshgod_Apocalypse01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8947\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse01.jpg\"                   alt=\"Fleshgod Apocalypse01\"                   title=\"Fleshgod Apocalypse01\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Fleshgod Apocalypse01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8946\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Destai_Designs_at_Mammothfest_2017.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8946\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Destai_Designs_at_Mammothfest_2017.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Destai_Designs_at_Mammothfest_2017.jpg\"                   alt=\"Destai Designs at Mammothfest 2017\"                   title=\"Destai Designs at Mammothfest 2017\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Destai Designs at Mammothfest 2017<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8945\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Bleed_Again01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8945\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Bleed_Again01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Bleed_Again01.jpg\"                   alt=\"Bleed Again01\"                   title=\"Bleed Again01\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Bleed Again01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8944\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Fleshgod_Apocalypse03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8944\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse03.jpg\"                   alt=\"Fleshgod Apocalypse03\"                   title=\"Fleshgod Apocalypse03\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Fleshgod Apocalypse03<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8943\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Fleshgod_Apocalypse02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8943\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse02.jpg\"                   alt=\"Fleshgod Apocalypse02\"                   title=\"Fleshgod Apocalypse02\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Fleshgod Apocalypse02<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8942\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Guttural_Carnage.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8942\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Guttural_Carnage.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Guttural_Carnage.jpg\"                   alt=\"Guttural Carnage\"                   title=\"Guttural Carnage\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Guttural Carnage<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8941\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Fleshgod_Apocalypse04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8941\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Fleshgod_Apocalypse04.jpg\"                   alt=\"Fleshgod Apocalypse04\"                   title=\"Fleshgod Apocalypse04\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Fleshgod Apocalypse04<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8940\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Kill_All_The_Gentlemen.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8940\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Kill_All_The_Gentlemen.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Kill_All_The_Gentlemen.jpg\"                   alt=\"Kill All The Gentlemen\"                   title=\"Kill All The Gentlemen\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Kill All The Gentlemen<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8939\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Guttural_Carnage01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8939\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Guttural_Carnage01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Guttural_Carnage01.jpg\"                   alt=\"Guttural Carnage01\"                   title=\"Guttural Carnage01\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Guttural Carnage01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8938\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Lagerstein01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8938\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein01.jpg\"                   alt=\"Lagerstein01\"                   title=\"Lagerstein01\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Lagerstein01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8937\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Dragged_Into_Sunlight.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8937\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Dragged_Into_Sunlight.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Dragged_Into_Sunlight.jpg\"                   alt=\"Dragged Into Sunlight\"                   title=\"Dragged Into Sunlight\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Dragged Into Sunlight<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8936\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Lagerstein.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8936\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein.jpg\"                   alt=\"Lagerstein\"                   title=\"Lagerstein\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Lagerstein<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8935\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Lagerstein02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8935\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein02.jpg\"                   alt=\"Lagerstein02\"                   title=\"Lagerstein02\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Lagerstein02<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8934\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Lagerstein03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8934\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein03.jpg\"                   alt=\"Lagerstein03\"                   title=\"Lagerstein03\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Lagerstein03<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8933\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/Lagerstein04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_1 \"                   data-id=\"8933\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D2_AG\/thumb\/Lagerstein04.jpg\"                   alt=\"Lagerstein04\"                   title=\"Lagerstein04\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Lagerstein04<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>          <span class=\"bwg_nav_cont_1\">              <div class=\"tablenav-pages_1\">                      <span class=\"pagination-links_1 pagination-links\" data-pages-count=\"2\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Go to the first page\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Go to the previous page\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_1\" onkeypress=\"return bwg_change_page_1(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tof\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_1\">\t\t\t\t\t\t\t\t\t\t\t2\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-1\" title=\"Go to the next page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/55719?page_number_1=2\">\u203a<\/a>                <a class=\"bwg-a last-page-1\" title=\"Go to the last page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/55719?page_number_1=2\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_1\" name=\"page_number_1\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_1').length > 1 ) {          jQuery('.bwg_nav_cont_1').first().remove()        }        function spider_page_1(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_1 = 2;          switch (y) {            case 1:              if (x >= items_county_1) {                document.getElementById('page_number_1').value = items_county_1;              }              else {                document.getElementById('page_number_1').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_1').value = items_county_1;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_1').value = 1;              }              else {                document.getElementById('page_number_1').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_1').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_1').value = x;              break;            default:              document.getElementById('page_number_1').value = 1;          }          bwg_ajax('gal_front_form_1', '1', 'bwg_thumbnails_1', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_1(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_1(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-1').on('click', function () {              spider_page_1(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-1').on('click', function () {              spider_page_1(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_1( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_1(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_1').on('click', function () {            spider_page_1(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>                <div id=\"bwg_spider_popup_loading_1\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_1\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_1\" value=\"882755654\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_1\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_1\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_1\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_1\"));            }          }        });      }    <\/script>    \n<p>Day 2 Line-up &#8212;<\/p>\n<p>The Arch Stage (Extreme Metal)<br \/>\n14:00 Kill All The Gentlemen<br \/>\n14:45 Bleed Again<br \/>\n15:30 Death Remains<br \/>\n16:15 Abhorrent Decimation<br \/>\n17:00 Metastasis<br \/>\n17:45 Lawnmower Deth<br \/>\n18:30 Akercocke<br \/>\n19:30 Dragged Into Sunlight<br \/>\n20:50 Fleshgod Apocalypse<\/p>\n<p>Rickstock Stage<br \/>\n14:00 Guttural Carnage<br \/>\n14:45 Hole In The Sky<br \/>\n15:30 Devil Wants Her Swagger Back<br \/>\n16:15 Synaptik<br \/>\n17:00 Damaj<br \/>\n17:45 Materia<br \/>\n18:30 Ascaris<br \/>\n19:15 Warcrab<br \/>\n20:10 No Raza<br \/>\n22:30 Lagerstein (VIP)<br \/>\n00:30 Seething Akira (VIP)<\/p>\n<p><!--nextpage--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Telepathy-d3.jpg\" alt=\"\" width=\"959\" height=\"400\" class=\"aligncenter size-full wp-image-55732\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Telepathy-d3.jpg 959w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Telepathy-d3-350x146.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Telepathy-d3-768x320.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/10\/Telepathy-d3-500x209.jpg 500w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><\/p>\n<p>The final day displayed some great Stoner and Doom acts like Ohhms, Grave Lines, headliners Belgians Amenra. A quick note from Pensevor, a band with a completely stripped down sound, which will appeal to Hardcore Doom fans, <em>&#8220;We&#8217;re trying to play music that is deliberately very regressive and primitive. Music that is opposed to technical showcasing and more immersed in brutally simplistic hypnotic riffs. We avoid traditional metal clich\u00e9s; instead we explore dissonance, feedback, irregular rhythms, extended passages of repeated patterns, drone and shrieked vocals, but still, sneak in some hooks to reassure the listener it&#8217;s still METAL. We intend to begin recording our second album in early 2018. Check out our debut album, Klothod, on Bandcamp:<br \/>\n<a href=\"http:\/\/pensevor432.bandcamp.com\/album\/pensevor\" rel=\"noopener\" target=\"_blank\">http:\/\/pensevor432.bandcamp.com\/album\/pensevor<\/a>&#8220;<\/em><\/p>\n<p>It is impossible not to mention a Hardcore Trash band Confronted, whose frontman was stunning the by-passers with hysterical expressions and whacking his drum which at times landed upon his head, he kept running off the stage and end ended up in all sorts of unusual places, behind the bar, on the bar, on the floor, outside&#8230; keeping the guy holding the microphone cable on his toes.<\/p>\n<h3>Mammothfest 2017 Day 3 Photo Gallery<\/h3>\n    <div id=\"bwg_container1_2\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"1\"         data-bwg=\"2\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/online\/wp-json\/wp\/v2\/posts\/55719\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=2&#038;gallery_id=192&#038;tag=0&#038;theme_id=1&#038;shortcode_id=199&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F55719\"         data-gallery-id=\"192\"         data-popup-width=\"800\"         data-popup-height=\"600\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_2\">             <div id=\"ajax_loading_2\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_2\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_2\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"2\"              data-shortcode-id=\"199\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"192\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_2\" class=\"bwg-background bwg-background-2\">                <div data-max-count=\"5\"         data-thumbnail-width=\"180\"         data-bwg=\"2\"         data-gallery-id=\"192\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=2&amp;gallery_id=192&amp;tag=0&amp;theme_id=1&amp;shortcode_id=199&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F55719\"         id=\"bwg_thumbnails_2\"         class=\"bwg-container-2 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9019\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Amenra.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9019\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Amenra.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Amenra.jpg\"                   alt=\"Amenra\"                   title=\"Amenra\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Amenra<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9018\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Amenra01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9018\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Amenra01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Amenra01.jpg\"                   alt=\"Amenra\"                   title=\"Amenra\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Amenra<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9017\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Chubby_Thunderous_Bad_Kush_Masters01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9017\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Chubby_Thunderous_Bad_Kush_Masters01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Chubby_Thunderous_Bad_Kush_Masters01.jpg\"                   alt=\"Chubby Thunderous Bad Kush Masters\"                   title=\"Chubby Thunderous Bad Kush Masters\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Chubby Thunderous Bad Kush Masters<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9016\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Amenra02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9016\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Amenra02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Amenra02.jpg\"                   alt=\"Amenra\"                   title=\"Amenra\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Amenra<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9015\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Confronted.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9015\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted.jpg\"                   alt=\"Confronted\"                   title=\"Confronted\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Confronted<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9014\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Confronted01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9014\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted01.jpg\"                   alt=\"Confronted\"                   title=\"Confronted\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Confronted<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9013\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Chubby_Thunderous_Bad_Kush_Masters.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9013\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Chubby_Thunderous_Bad_Kush_Masters.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Chubby_Thunderous_Bad_Kush_Masters.jpg\"                   alt=\"Chubby Thunderous Bad Kush Masters\"                   title=\"Chubby Thunderous Bad Kush Masters\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Chubby Thunderous Bad Kush Masters<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9012\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Confronted02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9012\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted02.jpg\"                   alt=\"Confronted\"                   title=\"Confronted\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Confronted<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9011\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Confronted03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9011\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted03.jpg\"                   alt=\"Confronted\"                   title=\"Confronted\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Confronted<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9010\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Enslavement.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9010\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Enslavement.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Enslavement.jpg\"                   alt=\"Enslavement\"                   title=\"Enslavement\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Enslavement<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9009\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Confronted04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9009\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted04.jpg\"                   alt=\"Confronted\"                   title=\"Confronted\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Confronted<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9008\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Enslavement01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9008\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Enslavement01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Enslavement01.jpg\"                   alt=\"Enslavement\"                   title=\"Enslavement\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Enslavement<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9007\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Core_Of_Io.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9007\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Core_Of_Io.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Core_Of_Io.jpg\"                   alt=\"Core Of Io\"                   title=\"Core Of Io\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Core Of Io<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9006\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Confronted05.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9006\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted05.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Confronted05.jpg\"                   alt=\"Confronted\"                   title=\"Confronted\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Confronted<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9005\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Enslavement03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9005\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Enslavement03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Enslavement03.jpg\"                   alt=\"Enslavement\"                   title=\"Enslavement\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Enslavement<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9004\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Grave_Lines01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9004\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Grave_Lines01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Grave_Lines01.jpg\"                   alt=\"Grave Lines\"                   title=\"Grave Lines\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Grave Lines<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9003\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Grave_Lines02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9003\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Grave_Lines02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Grave_Lines02.jpg\"                   alt=\"Grave Lines\"                   title=\"Grave Lines\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Grave Lines<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9002\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Enslavement02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9002\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Enslavement02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Enslavement02.jpg\"                   alt=\"Enslavement\"                   title=\"Enslavement\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Enslavement<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9001\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Grave_Lines.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9001\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Grave_Lines.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Grave_Lines.jpg\"                   alt=\"Grave Lines\"                   title=\"Grave Lines\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Grave Lines<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9000\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Haast&#039;s_Eagled01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"9000\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Haast&#039;s_Eagled01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Haast&#039;s_Eagled01.jpg\"                   alt=\"Haast&#039;s Eagled\"                   title=\"Haast&#039;s Eagled\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Haast's Eagled<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8999\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Kalloused.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8999\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Kalloused.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Kalloused.jpg\"                   alt=\"Kalloused\"                   title=\"Kalloused\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Kalloused<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8998\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Haast&#039;s_Eagled.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8998\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Haast&#039;s_Eagled.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Haast&#039;s_Eagled.jpg\"                   alt=\"Haast&#039;s Eagled\"                   title=\"Haast&#039;s Eagled\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Haast's Eagled<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8997\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Kalloused01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8997\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Kalloused01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Kalloused01.jpg\"                   alt=\"Kalloused\"                   title=\"Kalloused\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Kalloused<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8996\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Mutually_Assumed_Destruction01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8996\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Mutually_Assumed_Destruction01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Mutually_Assumed_Destruction01.jpg\"                   alt=\"Mutually Assumed Destruction\"                   title=\"Mutually Assumed Destruction\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Mutually Assumed Destruction<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8995\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Mammothfest_2017_team.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8995\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Mammothfest_2017_team.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Mammothfest_2017_team.jpg\"                   alt=\"Mammothfest 2017 team\"                   title=\"Mammothfest 2017 team\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Mammothfest 2017 team<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8994\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Mutually_Assumed_Destruction.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8994\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Mutually_Assumed_Destruction.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Mutually_Assumed_Destruction.jpg\"                   alt=\"Mutually Assumed Destruction\"                   title=\"Mutually Assumed Destruction\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Mutually Assumed Destruction<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8993\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Mutually_Assumed_Destruction02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8993\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Mutually_Assumed_Destruction02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Mutually_Assumed_Destruction02.jpg\"                   alt=\"Mutually Assumed Destruction\"                   title=\"Mutually Assumed Destruction\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Mutually Assumed Destruction<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8992\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Negative_Measures.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8992\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Negative_Measures.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Negative_Measures.jpg\"                   alt=\"Negative Measures\"                   title=\"Negative Measures\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Negative Measures<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8991\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/OHHMS01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8991\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/OHHMS01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/OHHMS01.jpg\"                   alt=\"OHHMS\"                   title=\"OHHMS\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">OHHMS<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"8990\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/Operation_Kino.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_2 \"                   data-id=\"8990\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Operation_Kino.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Mammothfest_D3_AG\/thumb\/Operation_Kino.jpg\"                   alt=\"Operation Kino\"                   title=\"Operation Kino\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Operation Kino<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>          <span class=\"bwg_nav_cont_2\">              <div class=\"tablenav-pages_2\">                      <span class=\"pagination-links_2 pagination-links\" data-pages-count=\"2\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Go to the first page\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Go to the previous page\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_2\" onkeypress=\"return bwg_change_page_2(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tof\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_2\">\t\t\t\t\t\t\t\t\t\t\t2\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-2\" title=\"Go to the next page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/55719?page_number_2=2\">\u203a<\/a>                <a class=\"bwg-a last-page-2\" title=\"Go to the last page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/55719?page_number_2=2\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_2\" name=\"page_number_2\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_2').length > 1 ) {          jQuery('.bwg_nav_cont_2').first().remove()        }        function spider_page_2(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_2 = 2;          switch (y) {            case 1:              if (x >= items_county_2) {                document.getElementById('page_number_2').value = items_county_2;              }              else {                document.getElementById('page_number_2').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_2').value = items_county_2;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_2').value = 1;              }              else {                document.getElementById('page_number_2').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_2').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_2').value = x;              break;            default:              document.getElementById('page_number_2').value = 1;          }          bwg_ajax('gal_front_form_2', '2', 'bwg_thumbnails_2', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_2(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_2(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-2').on('click', function () {              spider_page_2(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-2').on('click', function () {              spider_page_2(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_2( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_2(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_2').on('click', function () {            spider_page_2(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>                <div id=\"bwg_spider_popup_loading_2\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_2\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_2\" value=\"388440366\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_2\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_2\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_2\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_2\"));            }          }        });      }    <\/script>    \n<p>Day 3 Line-up &#8212;<\/p>\n<p>The Arch Stage (Stoner, Doom)<br \/>\n12:15 Solleme<br \/>\n13:00 Urne<br \/>\n13:45 Kalloused<br \/>\n14:30 Kurokuma<br \/>\n15:15 Haast&#8217;s Eagled<br \/>\n16:00 Wren<br \/>\n16:45 Grave Lines<br \/>\n17:30 Telepathy<br \/>\n18:15 Patrick Walker &#038; 40 Watt Sun<br \/>\n19:00 OHHMS<br \/>\n19:45 Vodun<br \/>\n21:00 Amenra<br \/>\n23:20 Chubby Thunderous Bad Kush Masters<\/p>\n<p>Rickstock Stage<br \/>\n12:30 Mutually Assured Destruction<br \/>\n13:15 Pensevor<br \/>\n14:00 Confronted<br \/>\n14:45 Thuum<br \/>\n15:30 This Is Turin<br \/>\n16:15 Negative Measures<br \/>\n17:00 Operation Kino<br \/>\n17:45 Enslavement<br \/>\n18:30 Thermit<br \/>\n19:00 Vigil<br \/>\n20:30 Core Of IO<\/p>\n<p>Official Websites:<br \/>\n<a href=\"http:\/\/www.mammothfest.uk\" target=\"_blank\" rel=\"noopener\">www.mammothfest.uk<\/a><br \/>\n<a href=\"http:\/\/www.facebook.com\/MammothfestUK\" target=\"_blank\" rel=\"noopener\">www.facebook.com\/MammothfestUK<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">by Arta Gailuma &#8211; Photojournalist &#8212; October 6 &#8211; 8, 2017 at The Arch in Brighton, England, UK &#8212; Friday was the shortest day but featured the biggest crowds to witness the Metal assault of <a class=\"mh-excerpt-more\" href=\"http:\/\/hardrockhaven.net\/online\/2017\/mammothfest-2017-concert-review-photo-gallery\/\" title=\"Mammothfest 2017\">[&#8230;]<\/a><\/div>\n","protected":false},"author":10,"featured_media":55733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15122],"tags":[12150,13783,13786,13809,13794,13781,13810,674,13813,13821,13792,13782,13791,13787,13818,13778,13788,13804,13789,13802,13777,13790,13800,13780,13801,13797,13785,13771,13793,13784,13811,13776,13816,13796,13807,13817,13806,13812,4221,13775,13798,13799,13779,9638,13805,13773,13819,13815,13814,13774,13772,13820,13808,13795,13803],"class_list":{"0":"post-55719","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arcconrvw2017","8":"tag-12150","9":"tag-abhorrent-decimation","10":"tag-akercocke","11":"tag-amenra","12":"tag-ascaris","13":"tag-bleed-again","14":"tag-chubby-thunderous-bad-kush-masters","15":"tag-concert","16":"tag-confronted","17":"tag-core-of-io","18":"tag-damaj","19":"tag-death-remains","20":"tag-devil-wants-her-swagger-back","21":"tag-dragged-into-sunlight","22":"tag-enslavement","23":"tag-ethereal-deitus","24":"tag-fleshgod-apocalypse","25":"tag-grave-lines","26":"tag-guttural-carnage","27":"tag-haasts-eagled","28":"tag-heathen-deity","29":"tag-hole-in-the-sky","30":"tag-kalloused","31":"tag-kill-all-the-gentlemen","32":"tag-kurokuma","33":"tag-lagerstein","34":"tag-lawnmower-deth","35":"tag-mammothfest","36":"tag-materia","37":"tag-metastasis","38":"tag-mutually-assured-destruction","39":"tag-necronautical","40":"tag-negative-measures","41":"tag-no-raza","42":"tag-ohhms","43":"tag-operation-kino","44":"tag-patrick-walker-40-watt-sun","45":"tag-pensevor","46":"tag-photo-gallery","47":"tag-rotting-christ","48":"tag-seething-akira","49":"tag-solleme-urne","50":"tag-sorrow-plagues","51":"tag-synaptik","52":"tag-telepathy","53":"tag-the-infernal-sea","54":"tag-thermit","55":"tag-this-is-turin","56":"tag-thuum","57":"tag-tsjuder","58":"tag-vehement","59":"tag-vigil","60":"tag-vodun","61":"tag-warcrab","62":"tag-wren"},"_links":{"self":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts\/55719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/comments?post=55719"}],"version-history":[{"count":0,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts\/55719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/media\/55733"}],"wp:attachment":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/media?parent=55719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/categories?post=55719"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/tags?post=55719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}