{"id":56387,"date":"2017-12-17T12:07:33","date_gmt":"2017-12-17T17:07:33","guid":{"rendered":"http:\/\/hardrockhaven.net\/online\/?p=56387"},"modified":"2018-04-18T19:15:39","modified_gmt":"2018-04-19T00:15:39","slug":"ruhrpott-metal-meeting-day-1-concert-review-photo-gallery","status":"publish","type":"post","link":"http:\/\/hardrockhaven.net\/online\/2017\/ruhrpott-metal-meeting-day-1-concert-review-photo-gallery\/","title":{"rendered":"Ruhrpott Metal Meeting: Day 1"},"content":{"rendered":"<blockquote><p><span style=\"text-decoration: underline;\">by Arta Gailuma<\/span><br \/>\n&#8211; Photojournalist &#8212;<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56413\" src=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/12\/2017-Max-Igor-Cavalera-Return-To-Roots.jpg\" alt=\"\" width=\"959\" height=\"400\" srcset=\"http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/12\/2017-Max-Igor-Cavalera-Return-To-Roots.jpg 959w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/12\/2017-Max-Igor-Cavalera-Return-To-Roots-350x146.jpg 350w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/12\/2017-Max-Igor-Cavalera-Return-To-Roots-768x320.jpg 768w, http:\/\/hardrockhaven.net\/online\/wp-content\/uploads\/2017\/12\/2017-Max-Igor-Cavalera-Return-To-Roots-500x209.jpg 500w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><\/p>\n<h3>December 08, 2017 at Turbinenhalle in Oberhausen, Germany &#8212;<\/h3>\n<h5>For the third year, Ruhrpott Metal Meeting was a gathering of black dressed music fans in German Oberhausen for good headbang just before Christmas.<\/h5>\n<p>Two days, two stages on Saturday with a strong line-up, a Metal market with CD&#8217;s, vinyl&#8217;s and all sorts of band memorabilia; an indoor beer garden, band signing sessions &#8230; basically, Ruhrpott has everything a proper festival can offer.<\/p>\n<p>The line up on Ruhrpott stage on Friday brought in a full room of people. Being a fan of Melodic Death Metal, I was especially excited to see Insomnium and Wolfheart and they definitely didn&#8217;t disappoint me or the rest of the fans. Even though the crowd was supportive for all bands, the moment New Jersey Thrash metallers Overkill appeared on stage it went simply mental-screaming, jumping, clapping hands and moshing. That madness continued with Max &amp; Igor Cavalera bringing their album <em>Roots<\/em> in full length to the stage.<\/p>\n<h3>Ruhrport Metal Meeting: Day 1 Concert Photo Gallery<\/h3>\n    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"1\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/online\/wp-json\/wp\/v2\/posts\/56387\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=201&#038;tag=0&#038;theme_id=1&#038;shortcode_id=410&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F56387\"         data-gallery-id=\"201\"         data-popup-width=\"800\"         data-popup-height=\"600\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"410\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"201\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"5\"         data-thumbnail-width=\"180\"         data-bwg=\"0\"         data-gallery-id=\"201\"         data-lightbox-url=\"http:\/\/hardrockhaven.net\/online\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=201&amp;tag=0&amp;theme_id=1&amp;shortcode_id=410&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fonline%2Fwp-json%2Fwp%2Fv2%2Fposts%2F56387\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9604\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Deserted_Fear.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9604\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear.jpg\"                   alt=\"Deserted Fear\"                   title=\"Deserted Fear\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deserted Fear<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9603\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Deserted_Fear03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9603\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear03.jpg\"                   alt=\"Deserted Fear\"                   title=\"Deserted Fear\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deserted Fear<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9602\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Deserted_Fear02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9602\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear02.jpg\"                   alt=\"Deserted Fear\"                   title=\"Deserted Fear\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deserted Fear<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9601\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Deserted_Fear04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9601\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear04.jpg\"                   alt=\"Deserted Fear\"                   title=\"Deserted Fear\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deserted Fear<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9600\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Deserted_Fear01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9600\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear01.jpg\"                   alt=\"Deserted Fear\"                   title=\"Deserted Fear\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deserted Fear<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9599\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Deserted_Fear05.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9599\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear05.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear05.jpg\"                   alt=\"Deserted Fear\"                   title=\"Deserted Fear\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deserted Fear<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9598\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Deserted_Fear06.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9598\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear06.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear06.jpg\"                   alt=\"Deserted Fear\"                   title=\"Deserted Fear\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deserted Fear<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9597\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Insomnium.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9597\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Insomnium.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Insomnium.jpg\"                   alt=\"Insomnium\"                   title=\"Insomnium\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Insomnium<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9596\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Deserted_Fear07.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9596\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear07.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Deserted_Fear07.jpg\"                   alt=\"Deserted Fear\"                   title=\"Deserted Fear\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Deserted Fear<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9595\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Max&#038;_Igor_Cavalera_Return_To_Roots.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9595\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots.jpg\"                   alt=\"Max &amp; Igor Cavalera Return To Roots\"                   title=\"Max &amp; Igor Cavalera Return To Roots\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Max &amp; Igor Cavalera Return To Roots<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9594\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Insomnium03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9594\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Insomnium03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Insomnium03.jpg\"                   alt=\"Insomnium\"                   title=\"Insomnium\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Insomnium<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9593\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Insomnium01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9593\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Insomnium01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Insomnium01.jpg\"                   alt=\"Insomnium\"                   title=\"Insomnium\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Insomnium<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9592\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Insomnium02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9592\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Insomnium02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Insomnium02.jpg\"                   alt=\"Insomnium\"                   title=\"Insomnium\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Insomnium<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9591\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Max&#038;_Igor_Cavalera_Return_To_Roots01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9591\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots01.jpg\"                   alt=\"Max &amp; Igor Cavalera Return To Roots\"                   title=\"Max &amp; Igor Cavalera Return To Roots\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Max &amp; Igor Cavalera Return To Roots<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9590\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Max&#038;_Igor_Cavalera_Return_To_Roots02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9590\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots02.jpg\"                   alt=\"Max &amp; Igor Cavalera Return To Roots\"                   title=\"Max &amp; Igor Cavalera Return To Roots\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Max &amp; Igor Cavalera Return To Roots<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9589\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Max&#038;_Igor_Cavalera_Return_To_Roots03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9589\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots03.jpg\"                   alt=\"Max &amp; Igor Cavalera Return To Roots\"                   title=\"Max &amp; Igor Cavalera Return To Roots\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Max &amp; Igor Cavalera Return To Roots<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9588\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Max&#038;_Igor_Cavalera_Return_To_Roots05.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9588\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots05.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots05.jpg\"                   alt=\"Max &amp; Igor Cavalera Return To Roots\"                   title=\"Max &amp; Igor Cavalera Return To Roots\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Max &amp; Igor Cavalera Return To Roots<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9587\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Max&#038;_Igor_Cavalera_Return_To_Roots06.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9587\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots06.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots06.jpg\"                   alt=\"Max &amp; Igor Cavalera Return To Roots\"                   title=\"Max &amp; Igor Cavalera Return To Roots\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Max &amp; Igor Cavalera Return To Roots<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9586\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Max&#038;_Igor_Cavalera_Return_To_Roots04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9586\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Max&#038;_Igor_Cavalera_Return_To_Roots04.jpg\"                   alt=\"Max &amp; Igor Cavalera Return To Roots\"                   title=\"Max &amp; Igor Cavalera Return To Roots\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Max &amp; Igor Cavalera Return To Roots<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9585\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Overkill.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9585\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill.jpg\"                   alt=\"Overkill\"                   title=\"Overkill\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Overkill<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9584\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Overkill01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9584\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill01.jpg\"                   alt=\"Overkill\"                   title=\"Overkill\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Overkill<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9583\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Overkill02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9583\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill02.jpg\"                   alt=\"Overkill\"                   title=\"Overkill\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Overkill<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9582\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Overkill03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9582\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill03.jpg\"                   alt=\"Overkill\"                   title=\"Overkill\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Overkill<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9581\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Overkill04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9581\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill04.jpg\"                   alt=\"Overkill\"                   title=\"Overkill\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Overkill<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9580\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Overkill06.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9580\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill06.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill06.jpg\"                   alt=\"Overkill\"                   title=\"Overkill\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Overkill<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9579\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Overkill05.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9579\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill05.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Overkill05.jpg\"                   alt=\"Overkill\"                   title=\"Overkill\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Overkill<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9578\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Ruhrpott_Metal_Meeting.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9578\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting.jpg\"                   alt=\"Ruhrpott Metal Meeting\"                   title=\"Ruhrpott Metal Meeting\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ruhrpott Metal Meeting<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9577\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Ruhrpott_Metal_Meeting03.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9577\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting03.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting03.jpg\"                   alt=\"Ruhrpott Metal Meeting\"                   title=\"Ruhrpott Metal Meeting\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ruhrpott Metal Meeting<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9576\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Ruhrpott_Metal_Meeting01.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9576\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting01.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting01.jpg\"                   alt=\"Ruhrpott Metal Meeting\"                   title=\"Ruhrpott Metal Meeting\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ruhrpott Metal Meeting<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9575\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Ruhrpott_Metal_Meeting02.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9575\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting02.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting02.jpg\"                   alt=\"Ruhrpott Metal Meeting\"                   title=\"Ruhrpott Metal Meeting\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ruhrpott Metal Meeting<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9574\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Ruhrpott_Metal_Meeting05.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9574\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting05.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting05.jpg\"                   alt=\"Ruhrpott Metal Meeting\"                   title=\"Ruhrpott Metal Meeting\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ruhrpott Metal Meeting<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9573\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Ruhrpott_Metal_Meeting04.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9573\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting04.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting04.jpg\"                   alt=\"Ruhrpott Metal Meeting\"                   title=\"Ruhrpott Metal Meeting\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ruhrpott Metal Meeting<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9572\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Ruhrpott_Metal_Meeting06.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9572\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting06.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting06.jpg\"                   alt=\"Ruhrpott Metal Meeting\"                   title=\"Ruhrpott Metal Meeting\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ruhrpott Metal Meeting<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9571\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Savage_Messiah.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9571\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Savage_Messiah.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Savage_Messiah.jpg\"                   alt=\"Savage Messiah\"                   title=\"Savage Messiah\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Savage Messiah<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"9570\" href=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/Ruhrpott_Metal_Meeting08.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"9570\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting08.jpg\"                   src=\"http:\/\/hardrockhaven.net\/online\/\/home\/hrhaven\/public_html\/online\/wp-content\/uploads\/\/photo-gallery\/2017\/2017_Ruhrport1_AG\/thumb\/Ruhrpott_Metal_Meeting08.jpg\"                   alt=\"Ruhrpott Metal Meeting\"                   title=\"Ruhrpott Metal Meeting\" \/>            <\/div>            <div class=\"\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">Ruhrpott Metal Meeting<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>          <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                      <span class=\"pagination-links_0 pagination-links\" data-pages-count=\"2\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Go to the first page\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Go to the previous page\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_0\" onkeypress=\"return bwg_change_page_0(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tof\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_0\">\t\t\t\t\t\t\t\t\t\t\t2\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-0\" title=\"Go to the next page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/56387?page_number_0=2\">\u203a<\/a>                <a class=\"bwg-a last-page-0\" title=\"Go to the last page\" href=\"\/online\/wp-json\/wp\/v2\/posts\/56387?page_number_0=2\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 2;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>                <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"146692988\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n<p>Ruhrpott Stage<br \/>\n23:00-00:20 Max &amp; Igor Cavalera Return To Roots<br \/>\n21:40-22:30 Overkill<br \/>\n20:30-21:20 Insomnium<br \/>\n19:30-20:10 Deserted Fear<br \/>\n18:300-19:10 Wolfheart<br \/>\n17:40-18:10 Savage Messiah<\/p>\n<p>Bands:<br \/>\n<a href=\"http:\/\/www.maxandiggorreturntoroots.com\" target=\"_blank\" rel=\"noopener\">www.maxandiggorreturntoroots.com<\/a><br \/>\n<a href=\"http:\/\/www.thewreckingcrew.com\" target=\"_blank\" rel=\"noopener\">www.thewreckingcrew.com<\/a><br \/>\n<a href=\"http:\/\/www.insomnium.net\" target=\"_blank\" rel=\"noopener\">www.insomnium.net<\/a><br \/>\n<a href=\"http:\/\/www.desertedfear.de\" target=\"_blank\" rel=\"noopener\">www.desertedfear.de<\/a><br \/>\n<a href=\"http:\/\/www.wolfheartofficial.com\" target=\"_blank\" rel=\"noopener\">www.wolfheartofficial.com<\/a><br \/>\n<a href=\"http:\/\/www.savagemessiahofficial.com\" target=\"_blank\" rel=\"noopener\">www.savagemessiahofficial.com<\/a><\/p>\n<p>Festival sites:<br \/>\n<a href=\"http:\/\/www.ruhrpott-metal-meeting.de\/\" target=\"_blank\" rel=\"noopener\">www.ruhrpott-metal-meeting.de\/<\/a><br \/>\n<a href=\"http:\/\/www.facebook.com\/RuhrpottMetalMeeting\/\" target=\"_blank\" rel=\"noopener\">www.facebook.com\/RuhrpottMetalMeeting\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">by Arta Gailuma &#8211; Photojournalist &#8212; December 08, 2017 at Turbinenhalle in Oberhausen, Germany &#8212; For the third year, Ruhrpott Metal Meeting was a gathering of black dressed music fans in German Oberhausen for good <a class=\"mh-excerpt-more\" href=\"http:\/\/hardrockhaven.net\/online\/2017\/ruhrpott-metal-meeting-day-1-concert-review-photo-gallery\/\" title=\"Ruhrpott Metal Meeting: Day 1\">[&#8230;]<\/a><\/div>\n","protected":false},"author":10,"featured_media":56413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15122],"tags":[674,3727,14006,9533,14007,1031,4221,334,14008,14004,8863,14005],"class_list":{"0":"post-56387","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arcconrvw2017","8":"tag-concert","9":"tag-day-1","10":"tag-deserted-fear","11":"tag-insomnium","12":"tag-max-igor-cavalera","13":"tag-overkill","14":"tag-photo-gallery","15":"tag-review","16":"tag-roots","17":"tag-ruhrport-metal-meeting","18":"tag-savage-messiah","19":"tag-wolfheart"},"_links":{"self":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts\/56387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/comments?post=56387"}],"version-history":[{"count":0,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/posts\/56387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/media\/56413"}],"wp:attachment":[{"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/media?parent=56387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/categories?post=56387"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hardrockhaven.net\/online\/wp-json\/wp\/v2\/tags?post=56387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}